{"id":54236,"date":"2021-08-23T05:27:23","date_gmt":"2021-08-23T10:27:23","guid":{"rendered":"https:\/\/tristanphotos.com\/?p=54236"},"modified":"2022-10-06T12:55:38","modified_gmt":"2022-10-06T17:55:38","slug":"kf-concept-national-geographic-backpack-review","status":"publish","type":"post","link":"https:\/\/tristanphotos.com\/es\/test-de-la-mochila-kf-concept-national-geographic\/","title":{"rendered":"Test de la Mochila de Foto K&amp;F Concept National Geographic"},"content":{"rendered":"<figure class=\"aligncenter wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Bolsa KF National Geographic\" style=\"object-fit:cover;\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10.jpg 600w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10-150x150.jpg 150w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10-300x300.jpg 300w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n<p>Independientemente de la c\u00e1mara que tengas o de si eres un profesional o un aficionado, una buena bolsa para la c\u00e1mara es una de las compras esenciales que debes hacer. <\/p>\n\n\n\n<p>Al fin y al cabo, es un compa\u00f1ero que usar\u00e1s a diario y que seg\u00fan sus cualidades influir\u00e1 en tu forma de hacer fotos.<\/p>\n\n\n\n<p>En este art\u00edculo te presentar\u00e9 la mochila K&amp;F National Geographic en todos sus aspectos<\/p>\n\n\n\n<p>Vayamos al meollo de la cuesti\u00f3n<\/p>\n\n\n<style>.kb-table-of-content-nav.kb-table-of-content-id_7c665d-62 .kb-table-of-content-wrap{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kb-table-of-content-nav.kb-table-of-content-id_7c665d-62 .kb-table-of-contents-title-wrap{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-table-of-content-nav.kb-table-of-content-id_7c665d-62 .kb-table-of-contents-title{font-weight:regular;font-style:normal;}.kb-table-of-content-nav.kb-table-of-content-id_7c665d-62 .kb-table-of-content-wrap .kb-table-of-content-list{font-weight:regular;font-style:normal;margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-right:0px;margin-bottom:0px;margin-left:0px;}<\/style>\n\n\n<h2 class=\"wp-block-heading\">Env\u00edo<\/h2>\n\n\n\n<p>En primer lugar, me impresion\u00f3 mucho el env\u00edo de este material. Despu\u00e9s de hacer el pedido en la p\u00e1gina web, el material lleg\u00f3 en s\u00f3lo 3 d\u00edas a casa en un paquete perfectamente embalado. Hay una plataforma de seguimiento que permite saber d\u00f3nde est\u00e1 la mochila en tiempo real, y seguir cada paso del env\u00edo con total confianza.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Llevar la bolsa<\/h2>\n\n\n\n<p>Al ir a menudo de senderismo por Colombia, o a largas sesiones fotogr\u00e1ficas en las ciudades, doy mucha importancia a la portabilidad de la bolsa. Al fin y al cabo, es lo que marca la diferencia al final del d\u00eda, \u00a1y tu espalda te lo agradecer\u00e1!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-0.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54237\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-0.jpg 500w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-0-250x300.jpg 250w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-0-10x12.jpg 10w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption>K&amp;F National Geographic Bag<\/figcaption><\/figure><\/div>\n\n\n\n<p>La bolsa es muy c\u00f3moda de llevar, las correas son gruesas y est\u00e1n bien acolchadas. Los clips del cintur\u00f3n son de un pl\u00e1stico resistente y duradero, lo que me permite apretar el cintur\u00f3n y llevar el 70% del peso de la bolsa con las caderas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Protecci\u00f3n de los equipos<\/h2>\n\n\n\n<p>La bolsa fotogr\u00e1fica k&amp;F Concept ofrece un conjunto de amplios separadores, de modo que los diferentes accesorios est\u00e1n muy bien protegidos unos de otros.<\/p>\n\n\n\n<p>En cuanto a la protecci\u00f3n externa, ya sea en la espalda o en la parte delantera de la bolsa, el acolchado es m\u00e1s que suficiente, por lo que soportar\u00e1n bien los golpes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-6.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54243\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-6.jpg 600w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-6-150x150.jpg 150w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-6-300x300.jpg 300w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-6-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>K&amp;F National Geographic Bag<\/figcaption><\/figure>\n\n\n\n<p>Otro detalle que apreci\u00e9 mucho es que el bolso viene con una funda para la lluvia directamente incluida lo cual es muy pr\u00e1ctico cuando se vive en los Andes colombianos y a menudo se dan las 4 estaciones en el mismo d\u00eda. Adem\u00e1s, m\u00e1s imposible olvidarlo tiene su peque\u00f1o bolsillo dedicado con un acceso r\u00e1pido<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-3.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54240\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-3.jpg 600w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-3-150x150.jpg 150w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-3-300x300.jpg 300w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-3-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>Bolsa KF National Geographic<\/figcaption><\/figure>\n\n\n\n<p>Por \u00faltimo, pero no menos importante, para acceder a los compartimentos de la c\u00e1mara debemos abrir las cremalleras traseras, abriendo as\u00ed la parte que quedar\u00eda a nuestra espalda para sacar la c\u00e1mara r\u00e9flex, lo que da un plus de seguridad ante posibles robos de tu equipo ante cualquier intento de hurto, perfecto si lo utilizas en el transporte p\u00fablico.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-7.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54244\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-7.jpg 600w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-7-150x150.jpg 150w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-7-300x300.jpg 300w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-7-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>Bolsa K&amp;F Concept National Geographic<\/figcaption><\/figure><\/div>\n\n\n\n<p>Para a\u00f1adir una capa adicional de protecci\u00f3n, la bolsa cuenta con una rejilla que te permite proteger tu equipo si alguna vez necesitas abrir la bolsa en una posici\u00f3n inc\u00f3moda. Tambi\u00e9n es muy pr\u00e1ctico cuando necesitas sacar tu equipo en lugares p\u00fablicos, te permite ocultar el equipo y no llamar demasiado la atenci\u00f3n de ojos mal\u00e9volos.<\/p>\n\n\n\n<p>A esto hay que a\u00f1adir que las cremalleras permiten cerrar la bolsa, muy pr\u00e1ctico cuando se viaja y se deja la bolsa en la habitaci\u00f3n del hotel, por ejemplo.s<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Calidad de los materiales y acabados<\/h2>\n\n\n\n<p>Estoy especialmente satisfecho con el acabado de la bolsa. La bolsa K&amp;F Concept inspira calidad y longevidad. <\/p>\n\n\n\n<p>Las cremalleras parecen ser irrompibles y las costuras de la bolsa no se mueven, incluso si tienes mucho peso en la bolsa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-1.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54238\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-1.jpg 500w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-1-250x300.jpg 250w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-1-10x12.jpg 10w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption>K&amp;F National Geographic Bag<\/figcaption><\/figure>\n\n\n\n<p>Asimismo, el material de construcci\u00f3n es resistente y parece repeler las salpicaduras. El tejido exterior tiene un revestimiento que le confiere una ligera protecci\u00f3n contra elementos como el polvo o la suciedad que no se adhieren, y la bolsa siempre permanece limpia.<\/p>\n\n\n\n<p> La base de la mochila tiene un revestimiento impermeable que la protege si se coloca sobre superficies h\u00famedas o mojadas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-2.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54239\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-2.jpg 600w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-2-150x150.jpg 150w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-2-300x300.jpg 300w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-2-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>K&amp;F National Geographic Bag<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Dise\u00f1o<\/h2>\n\n\n\n<p>El dise\u00f1o sigue siendo sobrio y moderno. Me gustan mucho sus tonos de color que se mezclan, sin llamar demasiado la atenci\u00f3n sobre el hecho de que se trata de una bolsa de c\u00e1mara con un equipo precioso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tama\u00f1o<\/h2>\n\n\n\n<p>Peque\u00f1a y compacta, la bolsa mide 31*<em>24<\/em>*46 cm, unos 23L lo que la convierte en una perfecta compa\u00f1era de viaje. Tiene el tama\u00f1o perfecto para colarse en el transporte p\u00fablico, cabe perfectamente en la cabina de los aviones, autobuses.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-4.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54241\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-4.jpg 500w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-4-250x300.jpg 250w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-4-10x12.jpg 10w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption>Bolsa KF National Geographic<\/figcaption><\/figure><\/div>\n\n\n\n<p>Y otro detalle que aprecio mucho es que cabe f\u00e1cilmente en el top case de mi moto (con el tr\u00edpode K&amp;F), muy c\u00f3modo cuando voy en moto por las carreteras de Colombia.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54247\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10.jpg 600w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10-150x150.jpg 150w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10-300x300.jpg 300w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>K&amp;F National Geographic Bag<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Capacidad de almacenamiento<\/h2>\n\n\n\n<p>La capacidad de carga es un gran punto a favor: el espacio interior de la bolsa es perfecto para cubrir casi cualquier escenario<\/p>\n\n\n\n<p>Los compartimentos se unen mediante velcro, pudiendo organizarlos como queramos, para una mejor colocaci\u00f3n de la c\u00e1mara, objetivos, cargadores, etc.<\/p>\n\n\n\n<p>B\u00e1sicamente, la bolsa de c\u00e1mara k&amp;f Concept puede contener 2 c\u00e1maras DSLR + 2 objetivos + tr\u00edpode + port\u00e1til de 14 pulgadas y otros accesorios de fotograf\u00eda<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-9.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54246\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-9.jpg 600w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-9-150x150.jpg 150w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-9-300x300.jpg 300w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-9-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>K&amp;F National Geographic Bag<\/figcaption><\/figure>\n\n\n\n<p>La bolsa tambi\u00e9n tiene suficientes bolsillos para albergar todos los accesorios adicionales de los fot\u00f3grafos, como un port\u00e1til de 13\", como un macbook, cables, lo que le permite albergar todo su flujo de trabajo fotogr\u00e1fico en un solo lugar<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-8.jpg\" alt=\"Bolsa KF National Geographic\" class=\"wp-image-54245\" srcset=\"https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-8.jpg 600w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-8-150x150.jpg 150w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-8-300x300.jpg 300w, https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-8-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>K&amp;F National Geographic Bag<\/figcaption><\/figure><\/div>\n\n\n\n<p>La bolsa tiene en su lateral un bolsillo dedicado y una correa para llevar el tr\u00edpode, lo que es muy pr\u00e1ctico y que faltaba en mi anterior mochila. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conveniencia<\/h2>\n\n\n\n<p>El acceso al equipamiento es muy f\u00e1cil. Las cremalleras son muy suaves y se puede sacar el equipo muy r\u00e1pidamente.<\/p>\n\n\n\n<p>Su gran capacidad permite albergar todo nuestro equipo fotogr\u00e1fico, sin necesidad de hacer y deshacer la bolsa despu\u00e9s de cada uso. Como resultado, la bolsa est\u00e1 siempre lista para salir al campo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Relaci\u00f3n calidad-precio<\/h2>\n\n\n\n<p>Cuando se trata del precio, la K&amp;F National Geographic es imbatible. Si bien es dif\u00edcil encontrar bolsos fotogr\u00e1ficos de calidad en Colombia o que los productos importados suelen tener un precio excesivo dada la tasa de cambio con el d\u00f3lar, sin embargo este bolso logra ofrecer un precio muy accesible, sin sacrificar la calidad.<\/p>\n\n\n\n<p>En general, una bolsa de esta calidad vale al menos 3 veces este precio<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPara qui\u00e9n es?<\/h2>\n\n\n\n<p>La bolsa se adapta por igual a aficionados, entusiastas y profesionales. Su flexibilidad y la reordenaci\u00f3n de sus espacios interiores le permiten llegar a todo tipo de fot\u00f3grafos con todo tipo de equipos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Satisfacci\u00f3n general<\/h2>\n\n\n\n<p>Las bolsas para c\u00e1maras son una parte vital de mi equipo. Desde que salgo regularmente al campo, he experimentado con algunas bolsas de diferentes tama\u00f1os para varios escenarios. y puedo decir que puedes llevar todo lo que quieras en esta espaciosa mochila.<\/p>\n\n\n\n<p>La K&amp;F Concept 13.119 es funcional, robusta, tiene buenos acabados y materiales y es elegante. En una palabra, no tiene nada que envidiar a las mochilas de gama alta.<\/p>\n\n\n\n<p>Con su excelente relaci\u00f3n calidad-precio, puedes comprar esta bolsa con los ojos cerrados, no te decepcionar\u00e1<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfD\u00f3nde comprar la mochila para c\u00e1maras K&amp;F Concept National Geographic?<\/h2>\n\n\n\n<p>In Colombia you find the  from 379.000 Cop directly on  a specialized photo store in Medellin.<\/p>\n\n\n\n<p>Si eres distribuidor y quieres comprarlo en mayores cantidades, PixelCamaras tambi\u00e9n tiene una oferta dedicada con mejores precios <\/p>","protected":false},"excerpt":{"rendered":"<p>Regardless of which camera you have or whether you are a professional or amateur, a good camera bag is one of the essential purchases that you need to make. After all, it is a companion that you will use every day and that according to its qualities will influence the way you take pictures. In&#8230;<\/p>","protected":false},"author":11,"featured_media":54247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"%%post_title%% (%%currentyear%%)","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","pgc_sgb_lightbox_settings":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[7224],"tags":[],"class_list":["post-54236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pictures"],"acf":[],"taxonomy_info":{"category":[{"value":7224,"label":"Pictures"}]},"featured_image_src_large":["https:\/\/tristanphotos.com\/wp-content\/uploads\/2021\/08\/KF-National-Geographic-Bag-10.jpg",600,600,false],"author_info":{"display_name":"Tristan Quevilly","author_link":"https:\/\/tristanphotos.com\/es\/author\/tristanquevilly\/"},"comment_info":95,"category_info":[{"term_id":7224,"name":"Pictures","slug":"pictures","term_group":0,"term_taxonomy_id":7224,"taxonomy":"category","description":"","parent":0,"count":16,"filter":"raw","cat_ID":7224,"category_count":16,"category_description":"","cat_name":"Pictures","category_nicename":"pictures","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/posts\/54236"}],"collection":[{"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/comments?post=54236"}],"version-history":[{"count":0,"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/posts\/54236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/media\/54247"}],"wp:attachment":[{"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/media?parent=54236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/categories?post=54236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tristanphotos.com\/es\/wp-json\/wp\/v2\/tags?post=54236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}